{"id":20872,"date":"2020-12-31T05:10:52","date_gmt":"2020-12-31T05:10:52","guid":{"rendered":"https:\/\/ex-tra.eutrailers\/"},"modified":"2024-06-24T17:32:32","modified_gmt":"2024-06-24T17:32:32","slug":"trailers","status":"publish","type":"page","link":"https:\/\/ex-tra.eu\/es\/trailers\/","title":{"rendered":"REMOLQUES"},"content":{"rendered":"<div class=\"wpb-content-wrapper\"><p>[vc_row gap=\u00bb30&#8243; content_placement=\u00bbmiddle\u00bb css=\u00bb.vc_custom_1514979444160{margin-top: 50px !important;}\u00bb][vc_column][vc_column_text]<\/p>\n<p style=\"text-align: left;\">EX-TRA tiene franjas horarias de producci\u00f3n con los principales fabricantes de veh\u00edculos de transporte especial.<br \/>\nEntre sus productos puede encontrar, desde contenedores con chasis divisible, hasta remolques triple extensibles.<\/p>\n<p style=\"text-align: left;\">Si la gama de remolques est\u00e1ndar no se ajusta a sus necesidades, EX-TRA tambi\u00e9n puede ofrecer remolques fabricados seg\u00fan sus especificaciones exactas.<\/p>\n<p style=\"text-align: left;\">EX-TRA tambi\u00e9n suministra los sistemas modulares Goldhofer para el sector de transporte pesado. Usted estar\u00e1 en la direcci\u00f3n correcta con ex-tra!<\/p>\n<p style=\"text-align: left;\">Sus ventajas:<\/p>\n<ul>\n<li>Plazos de entrega cortos para veh\u00edculos est\u00e1ndar<\/li>\n<li>Especificaciones totalmente a la medida<\/li>\n<li>Soluciones de transporte con una capacidad de carga hasta 10.000T<\/li>\n<\/ul>\n<p>[\/vc_column_text][vc_empty_space height=\u00bb15px\u00bb][\/vc_column][\/vc_row][vc_row css=\u00bb.vc_custom_1609399537459{margin-top: 20px !important;}\u00bb][vc_column width=\u00bb1\/3&#8243; css=\u00bb.vc_custom_1609400304079{padding-bottom: px !important;}\u00bb][vc_single_image image=\u00bb20370&#8243; img_size=\u00bbfull\u00bb onclick=\u00bbcustom_link\u00bb css=\u00bb\u00bb link=\u00bbhttps:\/\/ex-tra.eu\/es\/ex-centric-2&#8243;][\/vc_column][vc_column width=\u00bb1\/3&#8243; css=\u00bb.vc_custom_1609400198597{padding-bottom: 0px !important;}\u00bb][vc_single_image image=\u00bb20350&#8243; img_size=\u00bbfull\u00bb onclick=\u00bbcustom_link\u00bb css=\u00bb\u00bb link=\u00bbhttps:\/\/ex-tra.eu\/es\/paitier\u00bb][\/vc_column][vc_column width=\u00bb1\/3&#8243; css=\u00bb.vc_custom_1609400321366{padding-bottom: 0px !important;}\u00bb][vc_single_image image=\u00bb20366&#8243; img_size=\u00bbfull\u00bb onclick=\u00bbcustom_link\u00bb css=\u00bb\u00bb link=\u00bbhttps:\/\/ex-tra.eu\/es\/ex-centric\u00bb][\/vc_column][\/vc_row][vc_row css=\u00bb.vc_custom_1609399537459{margin-top: 20px !important;}\u00bb][vc_column width=\u00bb1\/3&#8243; css=\u00bb.vc_custom_1609400304079{padding-bottom: px !important;}\u00bb][vc_single_image image=\u00bb20362&#8243; img_size=\u00bbfull\u00bb onclick=\u00bbcustom_link\u00bb css=\u00bb\u00bb link=\u00bbhttps:\/\/ex-tra.eu\/es\/ex-centric-3&#8243;][\/vc_column][vc_column width=\u00bb1\/3&#8243; css=\u00bb.vc_custom_1609400321366{padding-bottom: 0px !important;}\u00bb][vc_single_image image=\u00bb26698&#8243; img_size=\u00bbfull\u00bb onclick=\u00bbcustom_link\u00bb css=\u00bb\u00bb link=\u00bbhttps:\/\/ex-tra.eu\/es\/ex-tract\u00bb][\/vc_column][vc_column width=\u00bb1\/3&#8243; css=\u00bb.vc_custom_1609400321366{padding-bottom: 0px !important;}\u00bb][vc_single_image image=\u00bb20374&#8243; img_size=\u00bbfull\u00bb onclick=\u00bbcustom_link\u00bb css=\u00bb\u00bb link=\u00bbhttps:\/\/ex-tra.eu\/es\/ex-train-2&#8243;][\/vc_column][\/vc_row]<\/p>\n<\/div>","protected":false},"excerpt":{"rendered":"<p>[vc_row gap=\u00bb30&#8243; content_placement=\u00bbmiddle\u00bb css=\u00bb.vc_custom_1514979444160{margin-top: 50px !important;}\u00bb][vc_column][vc_column_text] EX-TRA tiene franjas horarias de producci\u00f3n con los principales fabricantes de veh\u00edculos de transporte especial. Entre sus productos puede encontrar, desde contenedores con chasis divisible, hasta remolques triple extensibles. Si la gama de remolques&#8230;<\/p>\n","protected":false},"author":1,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"_acf_changed":false,"_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"footnotes":""},"class_list":["post-20872","page","type-page","status-publish","hentry"],"acf":[],"aioseo_notices":[],"aioseo_head":"\n\t\t<!-- All in One SEO 4.9.10 - aioseo.com -->\n\t<meta name=\"description\" content=\"EX-TRA tiene franjas horarias de producci\u00f3n con los principales fabricantes de veh\u00edculos de transporte especial. Entre sus productos puede encontrar, desde contenedores con chasis divisible, hasta remolques triple extensibles. Si la gama de remolques est\u00e1ndar no se ajusta a sus necesidades, EX-TRA tambi\u00e9n puede ofrecer remolques fabricados seg\u00fan sus especificaciones exactas. EX-TRA tambi\u00e9n suministra los\" \/>\n\t<meta name=\"robots\" content=\"max-image-preview:large\" \/>\n\t<link rel=\"canonical\" href=\"https:\/\/ex-tra.eu\/es\/trailers\/\" \/>\n\t<meta name=\"generator\" content=\"All in One SEO (AIOSEO) 4.9.10\" \/>\n\t\t<meta property=\"og:locale\" content=\"es_ES\" \/>\n\t\t<meta property=\"og:site_name\" content=\"Ex-tra - Buitengewoon transport\" \/>\n\t\t<meta property=\"og:type\" content=\"article\" \/>\n\t\t<meta property=\"og:title\" content=\"REMOLQUES - Ex-tra\" \/>\n\t\t<meta property=\"og:description\" content=\"EX-TRA tiene franjas horarias de producci\u00f3n con los principales fabricantes de veh\u00edculos de transporte especial. Entre sus productos puede encontrar, desde contenedores con chasis divisible, hasta remolques triple extensibles. Si la gama de remolques est\u00e1ndar no se ajusta a sus necesidades, EX-TRA tambi\u00e9n puede ofrecer remolques fabricados seg\u00fan sus especificaciones exactas. EX-TRA tambi\u00e9n suministra los\" \/>\n\t\t<meta property=\"og:url\" content=\"https:\/\/ex-tra.eu\/es\/trailers\/\" \/>\n\t\t<meta property=\"article:published_time\" content=\"2020-12-31T05:10:52+00:00\" \/>\n\t\t<meta property=\"article:modified_time\" content=\"2024-06-24T17:32:32+00:00\" \/>\n\t\t<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n\t\t<meta name=\"twitter:title\" content=\"REMOLQUES - Ex-tra\" \/>\n\t\t<meta name=\"twitter:description\" content=\"EX-TRA tiene franjas horarias de producci\u00f3n con los principales fabricantes de veh\u00edculos de transporte especial. Entre sus productos puede encontrar, desde contenedores con chasis divisible, hasta remolques triple extensibles. Si la gama de remolques est\u00e1ndar no se ajusta a sus necesidades, EX-TRA tambi\u00e9n puede ofrecer remolques fabricados seg\u00fan sus especificaciones exactas. EX-TRA tambi\u00e9n suministra los\" \/>\n\t\t<script type=\"application\/ld+json\" class=\"aioseo-schema\">\n\t\t\t{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/ex-tra.eu\\\/es\\\/trailers\\\/#breadcrumblist\",\"itemListElement\":[{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/ex-tra.eu\\\/es\\\/#listItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/ex-tra.eu\\\/es\\\/\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/ex-tra.eu\\\/es\\\/trailers\\\/#listItem\",\"name\":\"REMOLQUES\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/ex-tra.eu\\\/es\\\/trailers\\\/#listItem\",\"position\":2,\"name\":\"REMOLQUES\",\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/ex-tra.eu\\\/es\\\/#listItem\",\"name\":\"Home\"}}]},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/ex-tra.eu\\\/es\\\/#organization\",\"name\":\"Ex-tra\",\"description\":\"Buitengewoon transport\",\"url\":\"https:\\\/\\\/ex-tra.eu\\\/es\\\/\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/ex-tra.eu\\\/es\\\/trailers\\\/#webpage\",\"url\":\"https:\\\/\\\/ex-tra.eu\\\/es\\\/trailers\\\/\",\"name\":\"REMOLQUES - Ex-tra\",\"description\":\"EX-TRA tiene franjas horarias de producci\\u00f3n con los principales fabricantes de veh\\u00edculos de transporte especial. Entre sus productos puede encontrar, desde contenedores con chasis divisible, hasta remolques triple extensibles. Si la gama de remolques est\\u00e1ndar no se ajusta a sus necesidades, EX-TRA tambi\\u00e9n puede ofrecer remolques fabricados seg\\u00fan sus especificaciones exactas. EX-TRA tambi\\u00e9n suministra los\",\"inLanguage\":\"es-ES\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/ex-tra.eu\\\/es\\\/#website\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/ex-tra.eu\\\/es\\\/trailers\\\/#breadcrumblist\"},\"datePublished\":\"2020-12-31T05:10:52+00:00\",\"dateModified\":\"2024-06-24T17:32:32+00:00\"},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/ex-tra.eu\\\/es\\\/#website\",\"url\":\"https:\\\/\\\/ex-tra.eu\\\/es\\\/\",\"name\":\"Ex-tra\",\"description\":\"Buitengewoon transport\",\"inLanguage\":\"es-ES\",\"publisher\":{\"@id\":\"https:\\\/\\\/ex-tra.eu\\\/es\\\/#organization\"}}]}\n\t\t<\/script>\n\t\t<!-- All in One SEO -->\n\n","aioseo_head_json":{"title":"REMOLQUES - Ex-tra","description":"EX-TRA tiene franjas horarias de producci\u00f3n con los principales fabricantes de veh\u00edculos de transporte especial. Entre sus productos puede encontrar, desde contenedores con chasis divisible, hasta remolques triple extensibles. Si la gama de remolques est\u00e1ndar no se ajusta a sus necesidades, EX-TRA tambi\u00e9n puede ofrecer remolques fabricados seg\u00fan sus especificaciones exactas. EX-TRA tambi\u00e9n suministra los","canonical_url":"https:\/\/ex-tra.eu\/es\/trailers\/","robots":"max-image-preview:large","keywords":"","webmasterTools":{"miscellaneous":""},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"BreadcrumbList","@id":"https:\/\/ex-tra.eu\/es\/trailers\/#breadcrumblist","itemListElement":[{"@type":"ListItem","@id":"https:\/\/ex-tra.eu\/es\/#listItem","position":1,"name":"Home","item":"https:\/\/ex-tra.eu\/es\/","nextItem":{"@type":"ListItem","@id":"https:\/\/ex-tra.eu\/es\/trailers\/#listItem","name":"REMOLQUES"}},{"@type":"ListItem","@id":"https:\/\/ex-tra.eu\/es\/trailers\/#listItem","position":2,"name":"REMOLQUES","previousItem":{"@type":"ListItem","@id":"https:\/\/ex-tra.eu\/es\/#listItem","name":"Home"}}]},{"@type":"Organization","@id":"https:\/\/ex-tra.eu\/es\/#organization","name":"Ex-tra","description":"Buitengewoon transport","url":"https:\/\/ex-tra.eu\/es\/"},{"@type":"WebPage","@id":"https:\/\/ex-tra.eu\/es\/trailers\/#webpage","url":"https:\/\/ex-tra.eu\/es\/trailers\/","name":"REMOLQUES - Ex-tra","description":"EX-TRA tiene franjas horarias de producci\u00f3n con los principales fabricantes de veh\u00edculos de transporte especial. Entre sus productos puede encontrar, desde contenedores con chasis divisible, hasta remolques triple extensibles. Si la gama de remolques est\u00e1ndar no se ajusta a sus necesidades, EX-TRA tambi\u00e9n puede ofrecer remolques fabricados seg\u00fan sus especificaciones exactas. EX-TRA tambi\u00e9n suministra los","inLanguage":"es-ES","isPartOf":{"@id":"https:\/\/ex-tra.eu\/es\/#website"},"breadcrumb":{"@id":"https:\/\/ex-tra.eu\/es\/trailers\/#breadcrumblist"},"datePublished":"2020-12-31T05:10:52+00:00","dateModified":"2024-06-24T17:32:32+00:00"},{"@type":"WebSite","@id":"https:\/\/ex-tra.eu\/es\/#website","url":"https:\/\/ex-tra.eu\/es\/","name":"Ex-tra","description":"Buitengewoon transport","inLanguage":"es-ES","publisher":{"@id":"https:\/\/ex-tra.eu\/es\/#organization"}}]},"og:locale":"es_ES","og:site_name":"Ex-tra - Buitengewoon transport","og:type":"article","og:title":"REMOLQUES - Ex-tra","og:description":"EX-TRA tiene franjas horarias de producci\u00f3n con los principales fabricantes de veh\u00edculos de transporte especial. Entre sus productos puede encontrar, desde contenedores con chasis divisible, hasta remolques triple extensibles. Si la gama de remolques est\u00e1ndar no se ajusta a sus necesidades, EX-TRA tambi\u00e9n puede ofrecer remolques fabricados seg\u00fan sus especificaciones exactas. EX-TRA tambi\u00e9n suministra los","og:url":"https:\/\/ex-tra.eu\/es\/trailers\/","article:published_time":"2020-12-31T05:10:52+00:00","article:modified_time":"2024-06-24T17:32:32+00:00","twitter:card":"summary_large_image","twitter:title":"REMOLQUES - Ex-tra","twitter:description":"EX-TRA tiene franjas horarias de producci\u00f3n con los principales fabricantes de veh\u00edculos de transporte especial. Entre sus productos puede encontrar, desde contenedores con chasis divisible, hasta remolques triple extensibles. Si la gama de remolques est\u00e1ndar no se ajusta a sus necesidades, EX-TRA tambi\u00e9n puede ofrecer remolques fabricados seg\u00fan sus especificaciones exactas. EX-TRA tambi\u00e9n suministra los"},"aioseo_meta_data":{"post_id":"20872","title":null,"description":null,"keywords":null,"keyphrases":{"focus":{"keyphrase":"","score":0,"analysis":{"keyphraseInTitle":{"score":0,"maxScore":9,"error":1}}},"additional":[]},"primary_term":null,"canonical_url":null,"og_title":null,"og_description":null,"og_object_type":"default","og_image_type":"default","og_image_url":null,"og_image_width":null,"og_image_height":null,"og_image_custom_url":null,"og_image_custom_fields":null,"og_video":"","og_custom_url":null,"og_article_section":null,"og_article_tags":null,"twitter_use_og":false,"twitter_card":"default","twitter_image_type":"default","twitter_image_url":null,"twitter_image_custom_url":null,"twitter_image_custom_fields":null,"twitter_title":null,"twitter_description":null,"schema":{"blockGraphs":[],"customGraphs":[],"default":{"data":{"Article":[],"Course":[],"Dataset":[],"FAQPage":[],"Movie":[],"Person":[],"Product":[],"ProductReview":[],"Car":[],"Recipe":[],"Service":[],"SoftwareApplication":[],"WebPage":[]},"graphName":"WebPage","isEnabled":true},"graphs":[]},"schema_type":"default","schema_type_options":null,"pillar_content":false,"robots_default":true,"robots_noindex":false,"robots_noarchive":false,"robots_nosnippet":false,"robots_nofollow":false,"robots_noimageindex":false,"robots_noodp":false,"robots_notranslate":false,"robots_max_snippet":"-1","robots_max_videopreview":"-1","robots_max_imagepreview":"large","priority":null,"frequency":"default","local_seo":null,"breadcrumb_settings":null,"limit_modified_date":false,"ai":null,"created":"2023-01-17 18:12:30","updated":"2025-06-17 13:11:37","seo_analyzer_scan_date":null},"aioseo_breadcrumb":"<div class=\"aioseo-breadcrumbs\"><span class=\"aioseo-breadcrumb\">\n\t\t\t<a href=\"https:\/\/ex-tra.eu\/es\/\" title=\"Home\">Home<\/a>\n\t\t<\/span><span class=\"aioseo-breadcrumb-separator\">&raquo;<\/span><span class=\"aioseo-breadcrumb\">\n\t\t\tREMOLQUES\n\t\t<\/span><\/div>","aioseo_breadcrumb_json":[{"label":"Home","link":"https:\/\/ex-tra.eu\/es\/"},{"label":"REMOLQUES","link":"https:\/\/ex-tra.eu\/es\/trailers\/"}],"_links":{"self":[{"href":"https:\/\/ex-tra.eu\/es\/wp-json\/wp\/v2\/pages\/20872","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/ex-tra.eu\/es\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/ex-tra.eu\/es\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/ex-tra.eu\/es\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/ex-tra.eu\/es\/wp-json\/wp\/v2\/comments?post=20872"}],"version-history":[{"count":15,"href":"https:\/\/ex-tra.eu\/es\/wp-json\/wp\/v2\/pages\/20872\/revisions"}],"predecessor-version":[{"id":27148,"href":"https:\/\/ex-tra.eu\/es\/wp-json\/wp\/v2\/pages\/20872\/revisions\/27148"}],"wp:attachment":[{"href":"https:\/\/ex-tra.eu\/es\/wp-json\/wp\/v2\/media?parent=20872"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}